﻿{"id":260,"date":"2013-01-30T16:46:33","date_gmt":"2013-01-30T15:46:33","guid":{"rendered":"http:\/\/www.cours-adom.com\/?page_id=260"},"modified":"2026-04-07T13:50:16","modified_gmt":"2026-04-07T12:50:16","slug":"5eme-et-4eme","status":"publish","type":"page","link":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/","title":{"rendered":"5eme et 4eme, le cycle central"},"content":{"rendered":"<a href=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2059 alignright\" style=\"border: 0px; margin: 5px 10px;\" alt=\"Cute Schoolboy Smiling In Classroom\" src=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg\" width=\"234\" height=\"350\" srcset=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg 1571w, https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme-200x300.jpg 200w, https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme-682x1024.jpg 682w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/a>\r\n<p style=\"text-align: justify;\">Le cycle central est consacr\u00e9 \u00e0 l&rsquo;<strong>\u00e9largissement des connaissances<\/strong>. En 4\u00e8me d\u00e9bute obligatoirement l&rsquo;apprentissage d&rsquo;une 2\u00e8me langue vivante et les programmes abordent des notions plus abstraites, le d\u00e9veloppement du raisonnement et de l&rsquo;argumentation. Un <strong>travail r\u00e9gulier<\/strong> s&rsquo;av\u00e8re <strong>indispensable<\/strong>.<\/p>\r\n<p style=\"text-align: justify;\">Lors des cours particuliers, l&rsquo;enseignant Cours Ado apprend \u00e0 votre enfant \u00e0 <strong>aller \u00e0 l&rsquo;essentiel<\/strong> afin d&rsquo;int\u00e9grer les nouvelles d\u00e9marches intellectuelles qui lui sont demand\u00e9es gr\u00e2ce \u00e0 l&rsquo;<a href=\"\/index.php\/aide-aux-devoirs\/\">aide aux devoirs<\/a> jusqu&rsquo;en 5\u00e8me, qui permet de travailler plusieurs mati\u00e8res ou gr\u00e2ce au <a href=\"\/index.php\/suivi-regulier\/\">suivi r\u00e9gulier<\/a> qui permet de <strong>poser des bases solides<\/strong> dans une mati\u00e8re.\r\nPour ceux qui souhaitent aller plus loin, l&rsquo;approfondissement permet d&rsquo;<strong>\u00e9largir les savoirs et savoir-faire<\/strong>.<\/p>\r\n\r\n<h5 style=\"text-align: left;\">Fran\u00e7ais<\/h5>\r\n<p style=\"text-align: justify;\">L&rsquo;\u00e9tude de la langue se met au service de la pratique constante de la lecture et de l&rsquo;expression \u00e9crite et orale. L&rsquo;enseignant travaille avec votre enfant\u00a0:<\/p>\r\n\r\n<ul>\r\n\t<li class=\"roseCA\">la grammaire, l&rsquo;orthographe et le lexique<\/li>\r\n\t<li class=\"roseCA\">l&rsquo;expression \u00e9crite : l&rsquo;\u00e9l\u00e8ve apprend \u00e0 r\u00e9diger un texte correct et coh\u00e9rent d&rsquo;une page et demie ou 2 pages \u2013 en fonction du niveau- en respectant les consignes donn\u00e9es<\/li>\r\n\t<li class=\"roseCA\">l&rsquo;expression orale : savoir \u00e9couter, raconter et s&rsquo;exprimer.<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<h5 style=\"text-align: left;\">Math\u00e9matiques<\/h5>\r\n<p style=\"text-align: justify;\">Les m\u00e9thodes de r\u00e9solution des probl\u00e8mes \u00e9voluent avec les connaissances des \u00e9l\u00e8ves. Le professeur travaille avec votre enfant les points suivants\u00a0:<\/p>\r\n<p style=\"text-align: justify;\">En 5\u00e8me\u00a0:<\/p>\r\n\r\n<ul>\r\n\t<li class=\"roseCA\">la proportionnalit\u00e9<\/li>\r\n\t<li class=\"roseCA\">les expressions litt\u00e9rales<\/li>\r\n\t<li class=\"roseCA\">le calcul sur les entiers et les d\u00e9cimaux<\/li>\r\n\t<li class=\"roseCA\">la g\u00e9om\u00e9trie<\/li>\r\n\t<li class=\"roseCA\">les grandeurs et mesures : longueurs, masses et dur\u00e9es, angles, aires, volumes<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<p style=\"text-align: justify;\">En 4\u00e8me\u00a0:<\/p>\r\n\r\n<ul>\r\n\t<li class=\"roseCA\">la proportionnalit\u00e9<\/li>\r\n\t<li class=\"roseCA\">le calcul num\u00e9rique\u00a0: fractions, puissances, calcul litt\u00e9ral, d\u00e9velopper une expression<\/li>\r\n\t<li class=\"roseCA\">la g\u00e9om\u00e9trie et Pythagore<\/li>\r\n\t<li class=\"roseCA\">les grandeurs et mesures\u00a0: aires et volumes, vitesse moyenne<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<h5 style=\"text-align: left;\">Histoire-g\u00e9ographie et \u00e9ducation civique<\/h5>\r\n<p style=\"text-align: justify;\">Le professeur aide votre enfant \u00e0 analyser des documents et \u00e0 exposer ses connaissances au travers de courts r\u00e9cits.<\/p>\r\n\r\n<h5 style=\"text-align: left;\">Pratique d&rsquo;une langue vivante \u00e9trang\u00e8re<\/h5>\r\n<p style=\"text-align: justify;\">En 4\u00e8me, les \u00e9l\u00e8ves d\u00e9couvrent une 2\u00e8me langue vivante \u00e9trang\u00e8re.\r\nCours Ado a d\u00e9velopp\u00e9 des modules efficaces pour appr\u00e9hender la pratique de ces langues vivantes.\r\nContactez votre responsable p\u00e9dagogique qui proposera la solution adapt\u00e9e \u00e0 votre situation.<\/p>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;260&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;156&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.8&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this page&quot;,&quot;legend&quot;:&quot;4.8\\\/5 - (156 votes)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;5eme et 4eme, le cycle central&quot;,&quot;width&quot;:&quot;117.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 117.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            4.8\/5 - (156 votes)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"Le cycle central est consacr\u00e9 \u00e0 l&rsquo;\u00e9largissement des connaissances. En 4\u00e8me d\u00e9bute obligatoirement l&rsquo;apprentissage d&rsquo;une 2\u00e8me langue vivante et les&hellip;","protected":false},"author":1,"featured_media":0,"parent":245,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-260","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cours particuliers 5\u00e8me - Cours particuliers 4\u00e8me<\/title>\n<meta name=\"description\" content=\"Cours particuliers \u00e0 domicile toutes mati\u00e8res pour les \u00e9l\u00e8ves des classes de 5\u00e8me et 4\u00e8me. Posez des bases solides pour la suite avec Cours Ado...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cours particuliers 5\u00e8me - Cours particuliers 4\u00e8me\" \/>\n<meta property=\"og:description\" content=\"Cours particuliers \u00e0 domicile toutes mati\u00e8res pour les \u00e9l\u00e8ves des classes de 5\u00e8me et 4\u00e8me. Posez des bases solides pour la suite avec Cours Ado...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/\" \/>\n<meta property=\"og:site_name\" content=\"Cours particuliers \u00e0 domicile et soutien scolaire pour le primaire, le coll\u00e8ge, le lyc\u00e9e et le bac + 2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/coursadofrance\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T12:50:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1571\" \/>\n\t<meta property=\"og:image:height\" content=\"2356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/\",\"url\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/\",\"name\":\"Cours particuliers 5\u00e8me - Cours particuliers 4\u00e8me\",\"isPartOf\":{\"@id\":\"https:\/\/www.cours-ado.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg\",\"datePublished\":\"2013-01-30T15:46:33+00:00\",\"dateModified\":\"2026-04-07T12:50:16+00:00\",\"description\":\"Cours particuliers \u00e0 domicile toutes mati\u00e8res pour les \u00e9l\u00e8ves des classes de 5\u00e8me et 4\u00e8me. Posez des bases solides pour la suite avec Cours Ado...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#primaryimage\",\"url\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg\",\"contentUrl\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.cours-ado.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coll\u00e8ge\",\"item\":\"https:\/\/www.cours-ado.com\/index.php\/college\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5eme et 4eme, le cycle central\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cours-ado.com\/#website\",\"url\":\"https:\/\/www.cours-ado.com\/\",\"name\":\"Cours ado, soutien scolaire et cours particuliers \u00e0 domicile\",\"description\":\"Soutien scolaire \u00e0 domicile toutes mati\u00e8res pour le primaire, coll\u00e8ge, lyc\u00e9e et bac+2. Aide aux devoirs, stage vacances, r\u00e9visions des examens\",\"publisher\":{\"@id\":\"https:\/\/www.cours-ado.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cours-ado.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cours-ado.com\/#organization\",\"name\":\"Cours Ado\",\"url\":\"https:\/\/www.cours-ado.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg\",\"contentUrl\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg\",\"width\":612,\"height\":204,\"caption\":\"Cours Ado\"},\"image\":{\"@id\":\"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/coursadofrance\/\",\"https:\/\/www.instagram.com\/coursadofrance\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cours particuliers 5\u00e8me - Cours particuliers 4\u00e8me","description":"Cours particuliers \u00e0 domicile toutes mati\u00e8res pour les \u00e9l\u00e8ves des classes de 5\u00e8me et 4\u00e8me. Posez des bases solides pour la suite avec Cours Ado...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/","og_locale":"fr_FR","og_type":"article","og_title":"Cours particuliers 5\u00e8me - Cours particuliers 4\u00e8me","og_description":"Cours particuliers \u00e0 domicile toutes mati\u00e8res pour les \u00e9l\u00e8ves des classes de 5\u00e8me et 4\u00e8me. Posez des bases solides pour la suite avec Cours Ado...","og_url":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/","og_site_name":"Cours particuliers \u00e0 domicile et soutien scolaire pour le primaire, le coll\u00e8ge, le lyc\u00e9e et le bac + 2","article_publisher":"https:\/\/www.facebook.com\/coursadofrance\/","article_modified_time":"2026-04-07T12:50:16+00:00","og_image":[{"width":1571,"height":2356,"url":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg","type":"image\/jpeg"}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/","url":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/","name":"Cours particuliers 5\u00e8me - Cours particuliers 4\u00e8me","isPartOf":{"@id":"https:\/\/www.cours-ado.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#primaryimage"},"image":{"@id":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg","datePublished":"2013-01-30T15:46:33+00:00","dateModified":"2026-04-07T12:50:16+00:00","description":"Cours particuliers \u00e0 domicile toutes mati\u00e8res pour les \u00e9l\u00e8ves des classes de 5\u00e8me et 4\u00e8me. Posez des bases solides pour la suite avec Cours Ado...","breadcrumb":{"@id":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#primaryimage","url":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg","contentUrl":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2013\/01\/eleve-4eme.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cours-ado.com\/index.php\/college\/5eme-et-4eme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cours-ado.com\/"},{"@type":"ListItem","position":2,"name":"Coll\u00e8ge","item":"https:\/\/www.cours-ado.com\/index.php\/college\/"},{"@type":"ListItem","position":3,"name":"5eme et 4eme, le cycle central"}]},{"@type":"WebSite","@id":"https:\/\/www.cours-ado.com\/#website","url":"https:\/\/www.cours-ado.com\/","name":"Cours ado, soutien scolaire et cours particuliers \u00e0 domicile","description":"Soutien scolaire \u00e0 domicile toutes mati\u00e8res pour le primaire, coll\u00e8ge, lyc\u00e9e et bac+2. Aide aux devoirs, stage vacances, r\u00e9visions des examens","publisher":{"@id":"https:\/\/www.cours-ado.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cours-ado.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cours-ado.com\/#organization","name":"Cours Ado","url":"https:\/\/www.cours-ado.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg","contentUrl":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg","width":612,"height":204,"caption":"Cours Ado"},"image":{"@id":"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/coursadofrance\/","https:\/\/www.instagram.com\/coursadofrance\/"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P2X8v1-4c","_links":{"self":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":41,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/260\/revisions"}],"predecessor-version":[{"id":27081,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/260\/revisions\/27081"}],"up":[{"embeddable":true,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/245"}],"wp:attachment":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/media?parent=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}