﻿{"id":19290,"date":"2022-09-12T14:57:11","date_gmt":"2022-09-12T13:57:11","guid":{"rendered":"https:\/\/www.cours-ado.com\/?page_id=19290"},"modified":"2022-09-13T14:45:57","modified_gmt":"2022-09-13T13:45:57","slug":"experience-cours-ado-lyon","status":"publish","type":"page","link":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/","title":{"rendered":"L\u2019exp\u00e9rience Cours Ado Lyon"},"content":{"rendered":"<a href=\"https:\/\/www.cours-ado.com\/index.php\/rhone-cours-particuliers-lyon\/\">Cours Ado Lyon<\/a> est une agence sp\u00e9cialis\u00e9e dans le <strong>soutien scolaire \u00e0 domicile<\/strong>, pour tous les \u00e9l\u00e8ves de la <u>primaire jusqu\u2019au bac +2<\/u> selon les mati\u00e8res.\r\n\r\nNotre \u00e9quipe est constitu\u00e9e de <a href=\"https:\/\/www.cours-ado.com\/index.php\/professeur-particulier-a-lyon\/\">professeurs particuliers<\/a> passionn\u00e9s, qui se d\u00e9placent \u00e0 votre domicile pour faciliter l\u2019apprentissage ou le rattrapage scolaire de votre enfant.\r\n\r\n<div class=\"div-float\">\r\n<div class=\"div-width10\">\r\n<img decoding=\"async\" src=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg\" alt=\"Temoignages Cours Ado Lyon\" height=\"230\" \/>\r\n<\/div>\r\n<div class=\"div-width90 padding-div\">\r\nNotre m\u00e9thode est <strong>test\u00e9e et approuv\u00e9e<\/strong> par de nombreux parents d\u2019\u00e9l\u00e8ves. D\u00e9couvrez ici les t\u00e9moignages de parents ravis, et m\u00eame de certains de nos professeurs particuliers \u00e0 Lyon ! \r\n\r\nPar exemple, selon Carole P., maman d\u2019un gar\u00e7on en classe de 2nde, <font class=\"txtGris\">\u201cCours Ado Lyon propose un accompagnement scolaire de tr\u00e8s grande qualit\u00e9. \u00c9coute du besoin, rapidit\u00e9 de mise en place, sens relationnel irr\u00e9prochable de sa directrice et de l\u2019\u00e9quipe. Depuis deux ans, nous sommes en mesure d\u2019affirmer la constance qualitative de cette soci\u00e9t\u00e9 bienveillante envers nos enfants et \u00e9galement, respectueuse de l\u2019investissement financier des parents !\u201d<\/font>.\r\n<\/div>\r\n<\/div>\r\n\r\n<h2>Cours Ado Lyon, un suivi possible pour chaque classe<\/h2>\r\nCours Ado Lyon vous assure le <font class=\"txtRose\"><strong>respect du programme scolaire<\/strong><\/font>. Nos \u00e9quipes sont form\u00e9es avec les nouveaut\u00e9s du programme chaque nouvelle ann\u00e9e, afin d\u2019aider votre enfant au mieux.\r\n\r\n<u>D\u00e8s la primaire<\/u>, des difficult\u00e9s peuvent se faire ressentir, et Cours Ado Lyon est l\u00e0 pour aider votre enfant \u00e0 commencer au mieux le d\u00e9but de sa scolarit\u00e9.\r\n\r\n<u>Au coll\u00e8ge<\/u>, la pr\u00e9sence d\u2019un professeur particulier peut aider votre enfant \u00e0 combler ses lacunes et \u00e0 ne pas prendre de retard qui serait difficile \u00e0 rattraper par la suite. Nos professeurs particuliers transmettent \u00e9galement des <strong>m\u00e9thodes d\u2019apprentissage<\/strong> pour aider chaque enfant \u00e0 r<a href=\"https:\/\/www.cours-ado.com\/index.php\/aide-aux-devoirs-lyon\/\">\u00e9viser et \u00e0 travailler<\/a> de mani\u00e8re ind\u00e9pendante entre les le\u00e7ons. \r\n\r\nL\u2019aide apport\u00e9e par l\u2019agence de soutien scolaire Cours ado Lyon peut servir \u00e0 <a href=\"https:\/\/www.cours-ado.com\/index.php\/stages-pre-rentree-lyon\/\">pr\u00e9parer une rentr\u00e9e<\/a> stressante, comme la toute premi\u00e8re rentr\u00e9e au lyc\u00e9e. Selon Mimo : <font class=\"txtGris\">\u201cCours ado Lyon est une structure g\u00e9niale qui a aid\u00e9 mon fils \u00e0 progresser pour une rentr\u00e9e au lyc\u00e9e en toute confiance ! Je recommande \u00e0 100%, le personnel est \u00e0 l&rsquo;\u00e9coute, disponible et p\u00e9dagogue ! Merci pour votre investissement\u201d<\/font>.\r\n\r\n<h3>La prise en compte des sp\u00e9cificit\u00e9s de chaque \u00e9l\u00e8ve<\/h3>\r\nCar chaque \u00e9l\u00e8ve est diff\u00e9rent, nous offrons \u00e0 nos professeurs des formations afin de pouvoir accompagner les enfants souffrant de troubles du comportement ou de difficult\u00e9s scolaires par exemple. \r\n\r\nVoici le t\u00e9moignage de Caro E. \u00e0 ce sujet : <font class=\"txtGris\">\u201cTr\u00e8s belle exp\u00e9rience, une aide sur mesure en fonction des besoins et des particularit\u00e9s des enfants. Pour ma part j&rsquo;ai fait appel \u00e0 cours Ado pour un enfant de 5\u00e8me et un en terminale. Je recommande cette agence qui a fait preuve de bienveillance et qui conna\u00eet bien les HPI et TDAH*.\u201d<\/font><i>(*HPI : Haut Potentiel Intellectuel et TDAH : Trouble d\u00e9ficit de l&rsquo;attention avec ou sans hyperactivit\u00e9 de l&rsquo;enfant)<\/i>\r\n\r\nPour cela, nous mettons tout en \u0153uvre pour trouver LE professeur particulier qui correspond \u00e0 chaque \u00e9l\u00e8ve. Merci \u00e0 Sonia B. pour son avis sur ce point : <font class=\"txtGris\">\u201cR\u00e9activit\u00e9, \u00e0 l&rsquo;\u00e9coute, s\u00e9rieux, professionnalisme, en un mot TOP ! La\u00ebtitia est une vraie perle, elle est \u00e0 l&rsquo;\u00e9coute de nos attentes, elle se met en 4 pour trouver le prof id\u00e9al pour notre enfant. Mon fils a suivi pendant plusieurs ann\u00e9es des cours de soutien en maths, j&rsquo;en ai \u00e9t\u00e9 tr\u00e8s contente ! Elle arrive \u00e0 cerner la personnalit\u00e9 de votre enfant et trouver le professeur qui lui correspondra parfaitement.\u201d<\/font>, tout comme Daly R. <font class=\"txtGris\">\u201cTr\u00e8s professionnel, tr\u00e8s bon suivi&#8230; Cours ado a le souci de trouver le professeur qui correspond \u00e0 l&rsquo;enfant. Les professeurs sont patients et tr\u00e8s attentifs aux \u00e9volutions de l&rsquo;enfant.\u201d<\/font>.\r\n\r\n<h2>Cours Ado Lyon, un suivi par mati\u00e8re dans le respect du programme scolaire<\/h2>\r\nComme chaque enfant est diff\u00e9rent, Cours Ado Lyon vous propose une aide dans chaque mati\u00e8re qui pose probl\u00e8me gr\u00e2ce \u00e0 des <a href=\"https:\/\/www.cours-ado.com\/index.php\/cours-particuliers-lyon\/\">cours particuliers<\/a>. Selon les facilit\u00e9s naturelles de chacun, ce sont en effet des mati\u00e8res compl\u00e8tement diff\u00e9rentes qui peuvent poser probl\u00e8me.\r\n\r\nBien s\u00fbr, les <a href=\"https:\/\/www.cours-ado.com\/index.php\/cours-de-maths-lyon\/\">math\u00e9matiques<\/a> sont souvent la b\u00eate noire des \u00e9l\u00e8ves. C\u2019\u00e9tait de la cas de la fille de Aur\u00e9lie L <font class=\"txtGris\">\u201cJe recommande vivement cette agence! Accueil tr\u00e8s professionnel, suivi rigoureux et exigent. Le professeur de math\u00e9matiques s\u00e9lectionn\u00e9 pour ma fille a r\u00e9ussi \u00e0 faire des miracles en quelques s\u00e9ances!\u201d<\/font>.\r\n\r\nCours Ado Lyon propose aussi du soutien scolaire dans toutes les autres mati\u00e8res du programme scolaire : fran\u00e7ais, anglais, physique-chimie, sciences et vie de la terre, espagnol, etc. \r\n\r\n<h2>Les t\u00e9moignages de nos professeurs particuliers \u00e0 Lyon<\/h2>\r\nBien s\u00fbr, l\u2019avis de nos professeurs particuliers en soutien scolaire compte aussi. Notre \u00e9quipe met au c\u0153ur de ses pr\u00e9occupations la <strong>transmission d\u2019outils p\u00e9dagogiques<\/strong> et de <strong>m\u00e9thodes d\u2019apprentissage<\/strong>, pour que tous nos professeurs se sentent \u00e9panouis dans leur m\u00e9tier et puissent transmettre efficacement leurs connaissances aux \u00e9l\u00e8ves.\r\n\r\n<div class=\"div-float\">\r\n<div class=\"div-width60 padding-div\" style=\"padding-left:0px;\">\r\nMerci \u00e0 Marianne pour son retour : <font class=\"txtGris\">\u201cCela fait maintenant plus de 6 mois que j&rsquo;ai int\u00e9gr\u00e9 l&rsquo;\u00e9quipe Cours Ado. C&rsquo;est un plaisir de travailler avec des personnes aussi dynamiques et \u00e0 l&rsquo;\u00e9coute. L&rsquo;Agence cible bien les \u00e9l\u00e8ves et les mettent en relation avec des professeurs ayant un profil correspondant \u00e0 leurs besoins. J&rsquo;ai pu travailler avec des \u00e9l\u00e8ves tr\u00e8s diff\u00e9rents les uns des autres et c&rsquo;est toujours tr\u00e8s agr\u00e9able de d\u00e9couvrir de nouvelles personnalit\u00e9s.\u201d<\/font>.\r\n\r\nEnfin, merci \u00e0 Valentine D. : <font class=\"txtGris\">\u201cAyant travaill\u00e9 pendant plus d\u2019un an chez Cours Ado, je tenais \u00e0 remercier l\u2019\u00e9quipe qui est tr\u00e8s chaleureuse et vraiment \u00e0 l\u2019\u00e9coute. Le travail avec les familles est agr\u00e9able ainsi que le travail avec l\u2019\u00e9quipe Cours Ado. Merci pour cette ann\u00e9e et pour ce que ce travail m\u2019a apport\u00e9.\u201d<\/font>.\r\n\r\nN\u2019h\u00e9sitez pas \u00e0 nous contacter pour toute demande de soutien scolaire \u00e0 domicile dans la zone de Lyon et sa p\u00e9riph\u00e9rie.\r\n<\/div>\r\n<div class=\"div-width40\">\r\n<img decoding=\"async\" src=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/01\/equipe-professeurs-particuliers-lyon.jpg\" alt=\"Atelier professeurs Cours Ado Lyon\" \/>\r\n<\/div>\r\n<\/div>\r\n\r\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;19290&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this page&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;L\u2019exp\u00e9rience Cours Ado Lyon&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            <span class=\"kksr-muted\">Rate this page<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"Cours Ado Lyon est une agence sp\u00e9cialis\u00e9e dans le soutien scolaire \u00e0 domicile, pour tous les \u00e9l\u00e8ves de la primaire&hellip;","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-19290","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019exp\u00e9rience Cours Ado Lyon<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les retours clients et les avis des parents d&#039;\u00e9l\u00e8ves concernant nos cours particuliers \u00e0 domicile sur le secteur de Lyon et sa p\u00e9riph\u00e9rie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019exp\u00e9rience Cours Ado Lyon\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les retours clients et les avis des parents d&#039;\u00e9l\u00e8ves concernant nos cours particuliers \u00e0 domicile sur le secteur de Lyon et sa p\u00e9riph\u00e9rie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/\" \/>\n<meta property=\"og:site_name\" content=\"Cours particuliers \u00e0 domicile et soutien scolaire pour le primaire, le coll\u00e8ge, le lyc\u00e9e et le bac + 2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/coursadofrance\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-13T13:45:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/\",\"url\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/\",\"name\":\"L\u2019exp\u00e9rience Cours Ado Lyon\",\"isPartOf\":{\"@id\":\"https:\/\/www.cours-ado.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg\",\"datePublished\":\"2022-09-12T13:57:11+00:00\",\"dateModified\":\"2022-09-13T13:45:57+00:00\",\"description\":\"D\u00e9couvrez les retours clients et les avis des parents d'\u00e9l\u00e8ves concernant nos cours particuliers \u00e0 domicile sur le secteur de Lyon et sa p\u00e9riph\u00e9rie.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#primaryimage\",\"url\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg\",\"contentUrl\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg\",\"width\":1000,\"height\":1536,\"caption\":\"Temoignages Cours Ado Lyon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.cours-ado.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019exp\u00e9rience Cours Ado Lyon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cours-ado.com\/#website\",\"url\":\"https:\/\/www.cours-ado.com\/\",\"name\":\"Cours ado, soutien scolaire et cours particuliers \u00e0 domicile\",\"description\":\"Soutien scolaire \u00e0 domicile toutes mati\u00e8res pour le primaire, coll\u00e8ge, lyc\u00e9e et bac+2. Aide aux devoirs, stage vacances, r\u00e9visions des examens\",\"publisher\":{\"@id\":\"https:\/\/www.cours-ado.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cours-ado.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cours-ado.com\/#organization\",\"name\":\"Cours Ado\",\"url\":\"https:\/\/www.cours-ado.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg\",\"contentUrl\":\"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg\",\"width\":612,\"height\":204,\"caption\":\"Cours Ado\"},\"image\":{\"@id\":\"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/coursadofrance\/\",\"https:\/\/www.instagram.com\/coursadofrance\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019exp\u00e9rience Cours Ado Lyon","description":"D\u00e9couvrez les retours clients et les avis des parents d'\u00e9l\u00e8ves concernant nos cours particuliers \u00e0 domicile sur le secteur de Lyon et sa p\u00e9riph\u00e9rie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019exp\u00e9rience Cours Ado Lyon","og_description":"D\u00e9couvrez les retours clients et les avis des parents d'\u00e9l\u00e8ves concernant nos cours particuliers \u00e0 domicile sur le secteur de Lyon et sa p\u00e9riph\u00e9rie.","og_url":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/","og_site_name":"Cours particuliers \u00e0 domicile et soutien scolaire pour le primaire, le coll\u00e8ge, le lyc\u00e9e et le bac + 2","article_publisher":"https:\/\/www.facebook.com\/coursadofrance\/","article_modified_time":"2022-09-13T13:45:57+00:00","og_image":[{"url":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg","type":"","width":"","height":""}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/","url":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/","name":"L\u2019exp\u00e9rience Cours Ado Lyon","isPartOf":{"@id":"https:\/\/www.cours-ado.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#primaryimage"},"image":{"@id":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg","datePublished":"2022-09-12T13:57:11+00:00","dateModified":"2022-09-13T13:45:57+00:00","description":"D\u00e9couvrez les retours clients et les avis des parents d'\u00e9l\u00e8ves concernant nos cours particuliers \u00e0 domicile sur le secteur de Lyon et sa p\u00e9riph\u00e9rie.","breadcrumb":{"@id":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#primaryimage","url":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg","contentUrl":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/09\/temoignages-cours-particuliers-lyon.jpg","width":1000,"height":1536,"caption":"Temoignages Cours Ado Lyon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cours-ado.com\/index.php\/experience-cours-ado-lyon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cours-ado.com\/"},{"@type":"ListItem","position":2,"name":"L\u2019exp\u00e9rience Cours Ado Lyon"}]},{"@type":"WebSite","@id":"https:\/\/www.cours-ado.com\/#website","url":"https:\/\/www.cours-ado.com\/","name":"Cours ado, soutien scolaire et cours particuliers \u00e0 domicile","description":"Soutien scolaire \u00e0 domicile toutes mati\u00e8res pour le primaire, coll\u00e8ge, lyc\u00e9e et bac+2. Aide aux devoirs, stage vacances, r\u00e9visions des examens","publisher":{"@id":"https:\/\/www.cours-ado.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cours-ado.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cours-ado.com\/#organization","name":"Cours Ado","url":"https:\/\/www.cours-ado.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg","contentUrl":"https:\/\/www.cours-ado.com\/wp-content\/uploads\/2022\/03\/logo-cours-ado-soutien.jpg","width":612,"height":204,"caption":"Cours Ado"},"image":{"@id":"https:\/\/www.cours-ado.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/coursadofrance\/","https:\/\/www.instagram.com\/coursadofrance\/"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P2X8v1-518","_links":{"self":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/19290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/comments?post=19290"}],"version-history":[{"count":15,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/19290\/revisions"}],"predecessor-version":[{"id":19314,"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/pages\/19290\/revisions\/19314"}],"wp:attachment":[{"href":"https:\/\/www.cours-ado.com\/index.php\/wp-json\/wp\/v2\/media?parent=19290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}